{"id":837,"count":3,"description":"","link":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/","name":"Kardiologi Intervensi","slug":"kardiologi-intervensi","taxonomy":"content_tag","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arsip Kardiologi Intervensi - Health Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arsip Kardiologi Intervensi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/\" \/>\n<meta property=\"og:site_name\" content=\"Health Library\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arsip Kardiologi Intervensi - Health Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/","og_locale":"id_ID","og_type":"article","og_title":"Arsip Kardiologi Intervensi","og_url":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/","og_site_name":"Health Library","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/","url":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/","name":"Arsip Kardiologi Intervensi - Health Library","isPartOf":{"@id":"https:\/\/heartology.id\/health-library\/#website"},"breadcrumb":{"@id":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/heartology.id\/health-library\/content_tag\/kardiologi-intervensi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/heartology.id\/health-library\/"},{"@type":"ListItem","position":2,"name":"Kardiologi Intervensi"}]},{"@type":"WebSite","@id":"https:\/\/heartology.id\/health-library\/#website","url":"https:\/\/heartology.id\/health-library\/","name":"Health Library Heartology","description":"Wawasan dan Update Seputar Jantung dan Pembuluh Darah","publisher":{"@id":"https:\/\/heartology.id\/health-library\/#organization"},"alternateName":"Blog Heartology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heartology.id\/health-library\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/heartology.id\/health-library\/#organization","name":"PT Jakarta Pakar Kardia","alternateName":"JPK","url":"https:\/\/heartology.id\/health-library\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/heartology.id\/health-library\/#\/schema\/logo\/image\/","url":"https:\/\/heartology.id\/health-library\/wp-content\/uploads\/sites\/2\/2025\/04\/heartology-cardiovascular-hospital-logo-twoline-dark-300x197-1.png","contentUrl":"https:\/\/heartology.id\/health-library\/wp-content\/uploads\/sites\/2\/2025\/04\/heartology-cardiovascular-hospital-logo-twoline-dark-300x197-1.png","width":300,"height":197,"caption":"PT Jakarta Pakar Kardia"},"image":{"@id":"https:\/\/heartology.id\/health-library\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/heartology.id","https:\/\/www.instagram.com\/heartology.id\/","https:\/\/www.youtube.com\/@HeartologyCardiovascular","https:\/\/www.tiktok.com\/@heartology.id","https:\/\/www.linkedin.com\/company\/heartologyid\/"],"description":"Heartology Cardiovascular Hospital merupakan pusat unggulan dalam penanganan kondisi kardiovaskuler. Dengan dokter subspesialis berpengalaman yang didukung teknologi canggih dan tim medis berpengalaman.","email":"info@heartology.id","telephone":"(021) 5095 9955","legalName":"PT Jakarta Pakar Kardia","foundingDate":"2023-11-01","taxID":"940878622015000","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}}]}},"_links":{"self":[{"href":"https:\/\/heartology.id\/health-library\/wp-json\/wp\/v2\/content_tag\/837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heartology.id\/health-library\/wp-json\/wp\/v2\/content_tag"}],"about":[{"href":"https:\/\/heartology.id\/health-library\/wp-json\/wp\/v2\/taxonomies\/content_tag"}],"wp:post_type":[{"href":"https:\/\/heartology.id\/health-library\/wp-json\/wp\/v2\/content?content_tag=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}